{"id":9023,"date":"2021-05-20T20:00:04","date_gmt":"2021-05-20T18:00:04","guid":{"rendered":"http:\/\/www.toktali.com\/blog\/?p=9023"},"modified":"2021-12-16T17:25:51","modified_gmt":"2021-12-16T16:25:51","slug":"drogenmissbrauch-bei-politikern","status":"publish","type":"post","link":"https:\/\/www.toktali.com\/blog\/drogenmissbrauch-bei-politikern\/","title":{"rendered":"Drogenmissbrauch bei Politikern"},"content":{"rendered":"<p><a href=\"http:\/\/www.toktali.com\/blog\/wp-content\/uploads\/2014\/05\/elzin-tanzen.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9025 size-full\" src=\"http:\/\/www.toktali.com\/blog\/wp-content\/uploads\/2014\/05\/elzin-tanzen.jpg\" alt=\"elzin-tanzt\" width=\"500\" height=\"353\" srcset=\"https:\/\/www.toktali.com\/blog\/wp-content\/uploads\/2014\/05\/elzin-tanzen.jpg 500w, https:\/\/www.toktali.com\/blog\/wp-content\/uploads\/2014\/05\/elzin-tanzen-347x245.jpg 347w, https:\/\/www.toktali.com\/blog\/wp-content\/uploads\/2014\/05\/elzin-tanzen-482x340.jpg 482w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><em>Dick Swaab, geboren 1944, gilt als einer der international f\u00fchrenden Hirnforscher. \u201eWir sind unser Gehirn\u201c stand in den Niederlanden monatelang an der Spitze der Bestsellerliste. (Textausschnitt)<\/em><\/p>\n<p>Mit \u201eSucht\u201c assoziieren wir in erster Linie verwahrloste, obdachlose und oft schizophrene Menschen, und bei \u201eDrogenmissbrauch\u201c denkt man vielleicht an Borderline-Pers\u00f6nnlichkeitsst\u00f6rungen.<br \/>\nDoch der Neurologe David Owen, der unter anderem britischer Au\u00dfenminister und Mitglied des Oberhauses war, zeigt in seinem best\u00fcrzenden Buch \u201eIn Sickness and in Power\u201c (2008) auf, dass diese Problematik auch in den H\u00f6chsten Regierungskreisen eine Rolle spielt.<\/p>\n<p>Bill Clinton musste w\u00e4hrend seines Wahlkampfes 1992 unter schweren Druck eingestehen, dass er als Student Marihuana geraucht hatte.<br \/>\nW\u00e4hrend Barack Obamas Nominierungskampagne kam sein Buch \u201eDreams from my Father\u201c zur Sprache, in dem er bekennt als \u201everwirrter\u201c Teenager ein wenig gekokst und Marihuana geraucht zu haben.<br \/>\nGeorge W. Bush war vor seiner Pr\u00e4sidentschaft Alkoholiker, und das sicher nicht nur in der Pubert\u00e4t. Mit drei\u00dfig Jahren wurde er wegen Alkohol am Steuer festgenommen, und ihm wurde f\u00fcr zwei Jahre der F\u00fchrerschein entzogen.<br \/>\nBush weigerte sich \u00fcbrigens, Fragen zu seinem angeblichen Kokainkonsum zu beantworten.<br \/>\nAn Nixons Alkoholismus w\u00e4hrend seiner Pr\u00e4sidentschaft bestanden jedoch keinerlei Zweifel. 1969, w\u00e4hrend des Nordkorea-Zwischenfalls, bei dem ein amerikanisches Spionageflugzeug abgeschossen worden war, tobte Nixon sturzbetrunken herum und rief seinem Au\u00dfenminister Kissinger zu: \u201eHenri, wir schmei\u00dfen eine Atombombe drauf!\u201c<br \/>\nSeit 1994 nahm der russische Pr\u00e4sident Boris Jelzin immer mehr Schmerzmittel und Alkohol. Bei einer offiziellen Zeremonie, die 1994 zu Ehren des Abzugs der letzten russischen Truppen in Berlin stattfand, war er ganz offensichtlich betrunken.<br \/>\nUnd Alkohol ist gewiss nicht die einzige Droge, die Weltpolitiker w\u00e4hrend ihrer Amtsaus\u00fcbung konsumieren.<br \/>\nSollten wir von Politikern, die ein Land lenken, nicht wenigstens erwarten d\u00fcrfen, was wir von jedem verlangen, der ein Auto oder ein Flugzeug steuert?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dick Swaab, geboren 1944, gilt als einer der international f\u00fchrenden Hirnforscher. \u201eWir sind unser Gehirn\u201c stand in den Niederlanden monatelang an der Spitze der Bestsellerliste. (Textausschnitt) Mit \u201eSucht\u201c assoziieren wir in erster Linie verwahrloste, obdachlose und oft schizophrene Menschen, und bei \u201eDrogenmissbrauch\u201c denkt man vielleicht an Borderline-Pers\u00f6nnlichkeitsst\u00f6rungen. Doch der Neurologe David Owen, der unter anderem [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9025,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[659,709],"tags":[843,217],"class_list":["post-9023","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutsch","category-gesundheit","tag-alcoholism","tag-health"],"_links":{"self":[{"href":"https:\/\/www.toktali.com\/blog\/wp-json\/wp\/v2\/posts\/9023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.toktali.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.toktali.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.toktali.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.toktali.com\/blog\/wp-json\/wp\/v2\/comments?post=9023"}],"version-history":[{"count":0,"href":"https:\/\/www.toktali.com\/blog\/wp-json\/wp\/v2\/posts\/9023\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.toktali.com\/blog\/wp-json\/wp\/v2\/media\/9025"}],"wp:attachment":[{"href":"https:\/\/www.toktali.com\/blog\/wp-json\/wp\/v2\/media?parent=9023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.toktali.com\/blog\/wp-json\/wp\/v2\/categories?post=9023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.toktali.com\/blog\/wp-json\/wp\/v2\/tags?post=9023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}